{"id":3143,"date":"2020-07-08T15:10:15","date_gmt":"2020-07-08T18:10:15","guid":{"rendered":"https:\/\/www.scccheck.com.br\/blog\/?p=3143"},"modified":"2024-03-11T10:54:38","modified_gmt":"2024-03-11T13:54:38","slug":"o-que-sao-os-5cs-do-credito","status":"publish","type":"post","link":"https:\/\/www.scccheck.com.br\/blog\/o-que-sao-os-5cs-do-credito\/","title":{"rendered":"O que s\u00e3o os 5 C\u2019s do cr\u00e9dito e como us\u00e1-los em sua an\u00e1lise"},"content":{"rendered":"\n<p>Voc\u00ea, empres\u00e1rio, que se preocupa com a <strong>sa\u00fade financeira<\/strong> de seu neg\u00f3cio e est\u00e1 constantemente buscando formas de melhor\u00e1-la, muito provavelmente j\u00e1 ouviu falar sobre a t\u00e9cnica dos 5 C\u2019s. Mas voc\u00ea sabe exatamente<strong> o que s\u00e3o os 5 C\u2019s do cr\u00e9dito<\/strong>?<\/p>\n\n\n\n<p>N\u00f3s j\u00e1 tratamos ligeiramente sobre eles em uma outra mat\u00e9ria aqui do nosso blog, por\u00e9m, hoje, preparamos um conte\u00fado exclusivo para explicar cada um deles e, de quebra, trouxemos algumas dicas de <a href=\"https:\/\/www.scccheck.com.br\/solucoes\/\" target=\"_blank\" rel=\"noreferrer noopener\">consultas de cr\u00e9dito<\/a> que os colocam em pr\u00e1tica. <\/p>\n\n\n\n<p>Preparado para entender o assunto de maneira mais descomplicada?&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>T\u00e9cnica dos 5 C\u2019s: entenda a proposta de cada um!<\/strong><\/h2>\n\n\n\n<p>Investir em um produto para lan\u00e7ar no mercado, vend\u00ea-lo e n\u00e3o receber o pagamento, \u00e9 uma situa\u00e7\u00e3o bastante desagrad\u00e1vel, que nenhum empres\u00e1rio deseja passar. Mas a gente sabe que o risco existe, principalmente quando se vende a prazo, e \u00e9 nesse instante que o m\u00e9todo dos 5 C\u2019s entra em jogo.<\/p>\n\n\n\n<p>Antes de mais nada, \u00e9 v\u00e1lido esclarecer que essa estrat\u00e9gia n\u00e3o \u00e9 restrita apenas \u00e0s institui\u00e7\u00f5es financeiras. Empresas de variados segmentos podem aplic\u00e1-la para avaliar se seus clientes tamb\u00e9m oferecem o chamado<strong> risco de cr\u00e9dito<\/strong>. Afinal, tudo que est\u00e1 ligado a pagamento&nbsp;gera certa preocupa\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p>Os 5 C\u2019s, de forma simples, s\u00e3o uma esp\u00e9cie de <strong>estrutura de an\u00e1lise<\/strong> para verificar o perfil pagador que est\u00e1 por tr\u00e1s dos consumidores. Veja a seguir o que significa cada um desses elementos.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"492\" src=\"https:\/\/www.scccheck.com.br\/blog\/wp-content\/uploads\/2020\/07\/grafico_5cs-01-1024x492.png\" alt=\"\" class=\"wp-image-3165\" srcset=\"https:\/\/www.scccheck.com.br\/blog\/wp-content\/uploads\/2020\/07\/grafico_5cs-01-1024x492.png 1024w, https:\/\/www.scccheck.com.br\/blog\/wp-content\/uploads\/2020\/07\/grafico_5cs-01-300x144.png 300w, https:\/\/www.scccheck.com.br\/blog\/wp-content\/uploads\/2020\/07\/grafico_5cs-01-768x369.png 768w, https:\/\/www.scccheck.com.br\/blog\/wp-content\/uploads\/2020\/07\/grafico_5cs-01.png 1564w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Car\u00e1ter<\/strong><\/h3>\n\n\n\n<p>O primeiro se refere, logo de cara, ao <strong>hist\u00f3rico de pagamento <\/strong>do sujeito que realiza a compra ou que solicita o cr\u00e9dito. Aqui, \u00e9 analisado se essa pessoa costuma cumprir com seus compromissos financeiros, se respeita todos os prazos e d\u00edvidas.&nbsp;<\/p>\n\n\n\n<p>Por meio de uma consulta em um \u00f3rg\u00e3o de prote\u00e7\u00e3o ao cr\u00e9dito, como a <a href=\"https:\/\/www.serasaexperian.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Serasa Experian<\/a>, \u00e9 poss\u00edvel visualizar todas as <strong>opera\u00e7\u00f5es realizadas pelo solicitante<\/strong>, seja ele pessoa f\u00edsica ou jur\u00eddica.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Capacidade<\/strong><\/h3>\n\n\n\n<p>O segundo C diz respeito \u00e0 <strong>capacidade de pagamento<\/strong>. Nesse est\u00e1gio, observa-se, basicamente, o <strong>poder de compra<\/strong> do indiv\u00edduo.<\/p>\n\n\n\n<p>Em caso de pessoa f\u00edsicas, normalmente \u00e9 pedido um comprovante de renda, escritura de im\u00f3veis, declara\u00e7\u00e3o de imposto de renda, etc. Para empresas, \u00e9 identificado o tempo de mercado, fluxo e proje\u00e7\u00e3o de caixa, entre outras declara\u00e7\u00f5es financeiras.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Capital<\/strong><\/h3>\n\n\n\n<p>Qu\u00e3o s\u00f3lido financeiramente \u00e9 o seu cliente? Qual \u00e9 a <strong>taxa de rentabilidade <\/strong>dele, o <strong>poder de investimento<\/strong>? E o \u00edndice de endividamento? Essas perguntas s\u00e3o necess\u00e1rias para compreender se esse consumidor tem mais potencial para honrar com suas obriga\u00e7\u00f5es financeiras ou se pode oferecer algum tipo de risco ao seu neg\u00f3cio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Condi\u00e7\u00f5es<\/strong><\/h3>\n\n\n\n<p>\u00c9 importante entender a situa\u00e7\u00e3o em que o solicitante de cr\u00e9dito se encontra. Analisar o contexto econ\u00f4mico ao qual ele est\u00e1 inserido, junto a sua condi\u00e7\u00e3o de pagamento e as perspectivas do mercado, \u00e9 uma etapa essencial. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Colateral<\/strong><\/h3>\n\n\n\n<p>O \u00faltimo C est\u00e1 relacionado ao que o cliente deixa como <strong>garantia de que n\u00e3o ir\u00e1 falhar com suas responsabilidades financeiras<\/strong>. Exemplos comuns disso s\u00e3o im\u00f3veis, itens de valor, ve\u00edculos e outros bens materiais.&nbsp; <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Na pr\u00e1tica, como obter essas informa\u00e7\u00f5es?<\/strong><\/h2>\n\n\n\n<p>A import\u00e2ncia de ter acesso a esses dados \u00e9 enorme. Para conseguir todas essas informa\u00e7\u00f5es e garantir que sua<a href=\"https:\/\/www.scccheck.com.br\/blog\/primeiros-passos-para-implementar-a-analise-de-credito-em-sua-empresa\/\"> an\u00e1lise de cr\u00e9dito ser\u00e1 bem implementada<\/a> e eficiente, vale a pena apostar nas <strong>consultas de cr\u00e9dito<\/strong>.<\/p>\n\n\n\n<p>Na <strong>SCC Check<\/strong>, por exemplo, voc\u00ea encontra v\u00e1rias solu\u00e7\u00f5es dispon\u00edveis. Conhe\u00e7a as principais:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.scccheck.com.br\/solucao\/crednet-light\/\" target=\"_blank\" rel=\"noreferrer noopener\">Crednet Light<\/a>: recomendada para micro e pequenas empresas que atuam no mesmo estado, cujo prazo de pagamento ou de financiamento n\u00e3o seja longo em rela\u00e7\u00e3o a suas &#8220;contas a pagar&#8221;. A solu\u00e7\u00e3o \u00e9 uma vers\u00e3o resumida da Crednet Top, por isso, n\u00e3o apresenta quadro societ\u00e1rio e participa\u00e7\u00f5es societ\u00e1rias.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.scccheck.com.br\/solucao\/relatorio-simplificado-pf-e-pj\/\" target=\"_blank\" rel=\"noreferrer noopener\">Relat\u00f3rio simplificado PF e PJ<\/a>: possibilita os mesmos recursos que as institui\u00e7\u00f5es financeiras utilizam para avaliar cr\u00e9dito. \u00c9 basicamente uma Crednet Light mais aprofundada, com o acr\u00e9scimo de <strong>protestos nacionais<\/strong>, al\u00e9m dos estaduais, participa\u00e7\u00e3o em concordatas, fal\u00eancias e a\u00e7\u00f5es judiciais.&nbsp;<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.scccheck.com.br\/solucao\/relatorio-basico\/\" target=\"_blank\" rel=\"noreferrer noopener\">Relat\u00f3rio b\u00e1sico<\/a>:&nbsp;op\u00e7\u00e3o indicada para quem quer saber as d\u00edvidas dos seus clientes em todo territ\u00f3rio nacional, al\u00e9m do Score, para analisar melhor o futuro desses consumidores, atrav\u00e9s de uma avalia\u00e7\u00e3o mais parecida com a que \u00e9 feita pelos bancos e financeiras. <\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.scccheck.com.br\/solucao\/relatorio-avancado\/\" target=\"_blank\" rel=\"noreferrer noopener\">Relat\u00f3rio avan\u00e7ado<\/a>: na <strong>concess\u00e3o de cr\u00e9dito para<\/strong> <strong>PF<\/strong>: a consulta traz um quadro completo com informa\u00e7\u00f5es sobre a situa\u00e7\u00e3o atual e futura do documento analisado, hist\u00f3rico e comportamento no mercado e, por meio do <strong>Score<\/strong>, as chances e riscos de determinado cliente pagar ou n\u00e3o suas d\u00edvidas.\u00a0<br>Na <strong>concess\u00e3o de cr\u00e9dito para CNPJ:<\/strong> \u00e9 a mais completa, n\u00e3o importa qual seja o nicho de mercado. Com o relat\u00f3rio avan\u00e7ado, voc\u00ea tem acesso ao cadastro da empresa consultada, com informa\u00e7\u00f5es de comportamento financeiro dela e de seus s\u00f3cios, al\u00e9m de todo o hist\u00f3rico e chances de pagamento, classifica\u00e7\u00e3o de risco e muito mais.<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><a href=\"https:\/\/www.youtube.com\/watch?v=CSB7CZP84Qw&amp;utm_source=banner&amp;utm_medium=blog&amp;utm_campaign=5cs_credito\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"473\" src=\"https:\/\/www.scccheck.com.br\/blog\/wp-content\/uploads\/2024\/03\/banner-blog-serasa-recomenda-2-1024x473.png\" alt=\"\" class=\"wp-image-15555\" srcset=\"https:\/\/www.scccheck.com.br\/blog\/wp-content\/uploads\/2024\/03\/banner-blog-serasa-recomenda-2-1024x473.png 1024w, https:\/\/www.scccheck.com.br\/blog\/wp-content\/uploads\/2024\/03\/banner-blog-serasa-recomenda-2-300x139.png 300w, https:\/\/www.scccheck.com.br\/blog\/wp-content\/uploads\/2024\/03\/banner-blog-serasa-recomenda-2-768x355.png 768w, https:\/\/www.scccheck.com.br\/blog\/wp-content\/uploads\/2024\/03\/banner-blog-serasa-recomenda-2.png 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Comece suas an\u00e1lises de cr\u00e9dito agora!<\/strong><\/h2>\n\n\n\n<p>Essas foram apenas algumas alternativas de consultas que podem reunir dados essenciais sobre seu cliente. Agora que voc\u00ea j\u00e1 as conhece e sabe <strong>o que s\u00e3o os 5 C&#8217;s do cr\u00e9dito<\/strong>, basta escolher aquela que corresponde a necessidade do seu neg\u00f3cio e come\u00e7ar a analisar!<\/p>\n\n\n\n<p>Achou este post \u00fatil? Para conferir mais conte\u00fados com temas relacionados, \u00e9 s\u00f3 acompanhar nosso blog. Toda semana temos uma nova mat\u00e9ria por aqui.<\/p>\n\n\n\n<p>Se quiser, deixe um coment\u00e1rio com suas d\u00favidas e ideias. Ser\u00e1 um prazer te responder. At\u00e9 a pr\u00f3xima!&nbsp;<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea, empreendedor, que se preocupa com a sa\u00fade financeira de seu neg\u00f3cio e est\u00e1 constantemente buscando formas de melhor\u00e1-la, muito provavelmente j\u00e1 ouviu falar sobre a t\u00e9cnica dos 5 C\u2019s. Mas voc\u00ea sabe exatamente o que s\u00e3o os 5 C\u2019s do cr\u00e9dito?<\/p>\n","protected":false},"author":5,"featured_media":3163,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[23,9,2],"tags":[164,14,207,57],"class_list":["post-3143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analise-de-credito","category-destaques","category-negativacao-e-cobranca","tag-5-cs","tag-analise-de-credito","tag-risco-de-credito","tag-saude-financeira"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>O que s\u00e3o os 5 C\u2019s do cr\u00e9dito: entenda cada um deles!<\/title>\n<meta name=\"description\" content=\"\u00c9 bem prov\u00e1vel que voc\u00ea j\u00e1 tenha ouvido falar sobre os 5 C\u2019s do cr\u00e9dito, mas voc\u00ea sabe exatamente o que \u00e9 cada um deles? A gente te explica!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scccheck.com.br\/blog\/o-que-sao-os-5cs-do-credito\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.scccheck.com.br\/blog\/o-que-sao-os-5cs-do-credito\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.scccheck.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O que s\u00e3o os 5 C\u2019s do cr\u00e9dito e como us\u00e1-los em sua an\u00e1lise\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O que s\u00e3o os 5 C\u2019s do cr\u00e9dito: entenda cada um deles!","description":"\u00c9 bem prov\u00e1vel que voc\u00ea j\u00e1 tenha ouvido falar sobre os 5 C\u2019s do cr\u00e9dito, mas voc\u00ea sabe exatamente o que \u00e9 cada um deles? A gente te explica!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scccheck.com.br\/blog\/o-que-sao-os-5cs-do-credito\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.scccheck.com.br\/blog\/o-que-sao-os-5cs-do-credito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.scccheck.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"O que s\u00e3o os 5 C\u2019s do cr\u00e9dito e como us\u00e1-los em sua an\u00e1lise"}]}]},"og_image":[{"url":"https:\/\/www.scccheck.com.br\/blog\/wp-content\/uploads\/2020\/07\/adeolu-eletu-unRkg2jH1j0-unsplash.jpg"}]},"exibir_no_sistema":false,"_links":{"self":[{"href":"https:\/\/www.scccheck.com.br\/blog\/wp-json\/wp\/v2\/posts\/3143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scccheck.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.scccheck.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.scccheck.com.br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.scccheck.com.br\/blog\/wp-json\/wp\/v2\/comments?post=3143"}],"version-history":[{"count":43,"href":"https:\/\/www.scccheck.com.br\/blog\/wp-json\/wp\/v2\/posts\/3143\/revisions"}],"predecessor-version":[{"id":15556,"href":"https:\/\/www.scccheck.com.br\/blog\/wp-json\/wp\/v2\/posts\/3143\/revisions\/15556"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.scccheck.com.br\/blog\/wp-json\/wp\/v2\/media\/3163"}],"wp:attachment":[{"href":"https:\/\/www.scccheck.com.br\/blog\/wp-json\/wp\/v2\/media?parent=3143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.scccheck.com.br\/blog\/wp-json\/wp\/v2\/categories?post=3143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.scccheck.com.br\/blog\/wp-json\/wp\/v2\/tags?post=3143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}